{"id":2907,"date":"2025-04-09T15:12:25","date_gmt":"2025-04-09T11:42:25","guid":{"rendered":"https:\/\/we-are-havin.ir\/dds\/?p=2907"},"modified":"2025-04-09T15:20:13","modified_gmt":"2025-04-09T11:50:13","slug":"%d8%aa%d9%88%d8%b3%d8%b9%d9%87-%d9%88-%d9%86%d9%88%d8%b3%d8%a7%d8%b2%db%8c-%d9%86%d8%a7%d9%88%da%af%d8%a7%d9%86%d8%8c-%d9%87%d8%af%d9%81-%d8%b1%d8%a7%d9%87%d8%a8%d8%b1%d8%af%db%8c-%d9%86%d8%a7%d9%88","status":"publish","type":"post","link":"https:\/\/tarabaran.com\/en\/maritime-transport\/%d8%aa%d9%88%d8%b3%d8%b9%d9%87-%d9%88-%d9%86%d9%88%d8%b3%d8%a7%d8%b2%db%8c-%d9%86%d8%a7%d9%88%da%af%d8%a7%d9%86%d8%8c-%d9%87%d8%af%d9%81-%d8%b1%d8%a7%d9%87%d8%a8%d8%b1%d8%af%db%8c-%d9%86%d8%a7%d9%88\/","title":{"rendered":"\u062a\u0648\u0633\u0639\u0647 \u0648 \u0646\u0648\u0633\u0627\u0632\u06cc \u0646\u0627\u0648\u06af\u0627\u0646\u060c \u0647\u062f\u0641 \u0631\u0627\u0647\u0628\u0631\u062f\u06cc \u0646\u0627\u0648\u06af\u0627\u0646 \u0645\u0644\u06cc \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f4"},"content":{"rendered":"<h2><\/h2>\n<h2 class=\"main-news-page-sub-title\"><span style=\"color: #ff0000;\">\u062a\u0631\u0627\u0628\u0631\u0627\u0646 \u0622\u0646\u0644\u0627\u06cc\u0646:<\/span> \u0645\u062f\u0631\u0633 \u062e\u06cc\u0627\u0628\u0627\u0646\u06cc\u060c\u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0627\u0632 \u062a\u0648\u0633\u0639\u0647 \u0648 \u0646\u0648\u0633\u0627\u0632\u06cc \u0646\u0627\u0648\u06af\u0627\u0646 \u06a9\u0647 \u0627\u0632 \u0627\u0647\u062f\u0627\u0641 \u0631\u0627\u0647\u0628\u0631\u062f\u06cc \u0646\u0627\u0648\u06af\u0627\u0646 \u0645\u0644\u06cc \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f4 \u0627\u0633\u062a \u062e\u0628\u0631 \u062f\u0627\u062f.<\/h2>\n<div>\n<p>\u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0631\u0634\u062f \u06f1\u06f0\u06f8 \u062f\u0631\u0635\u062f\u06cc \u062f\u0631\u0622\u0645\u062f\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f3\u060c \u0627\u0632 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0631\u06cc\u0632\u06cc \u0628\u0631\u0627\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0628\u0647 \u06cc\u06a9 \u0634\u0631\u06a9\u062a \u0644\u062c\u0633\u062a\u06cc\u06a9\u06cc \u067e\u06cc\u0634\u0631\u0648 \u062f\u0631 \u0633\u0637\u062d \u0645\u0646\u0637\u0642\u0647 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f4 \u062e\u0628\u0631 \u062f\u0627\u062f \u0648 \u06af\u0641\u062a: \u062a\u0648\u0633\u0639\u0647 \u0648 \u0646\u0648\u0633\u0627\u0632\u06cc \u0646\u0627\u0648\u06af\u0627\u0646\u060c \u0647\u062f\u0641 \u0631\u0627\u0647\u0628\u0631\u062f\u06cc \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f4 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/p>\n<p><a href=\"https:\/\/we-are-havin.ir\/dds\/wp-content\/uploads\/2025\/04\/100335_201.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2949\" src=\"https:\/\/we-are-havin.ir\/dds\/wp-content\/uploads\/2025\/04\/100335_201-300x200.jpg\" alt=\"\" width=\"1124\" height=\"749\" srcset=\"https:\/\/tarabaran.com\/en\/wp-content\/uploads\/2025\/04\/100335_201-300x200.jpg 300w, https:\/\/tarabaran.com\/en\/wp-content\/uploads\/2025\/04\/100335_201-768x513.jpg 768w, https:\/\/tarabaran.com\/en\/wp-content\/uploads\/2025\/04\/100335_201-600x400.jpg 600w, https:\/\/tarabaran.com\/en\/wp-content\/uploads\/2025\/04\/100335_201.jpg 899w\" sizes=\"(max-width: 1124px) 100vw, 1124px\" \/><\/a><\/p>\n<h3><span style=\"color: #3366ff;\">\u062a\u0634\u062f\u06cc\u062f \u062a\u062d\u0631\u06cc\u0645\u200c\u0647\u0627<\/span><\/h3>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u062a\u0631\u0627\u0628\u0631\u0627 \u0622\u0646\u0644\u0627\u06cc\u0646\u060c \u0645\u062d\u0645\u062f\u0631\u0636\u0627 \u0645\u062f\u0631\u0633 \u062e\u06cc\u0627\u0628\u0627\u0646\u06cc \u062f\u0631 \u067e\u06cc\u0627\u0645 \u0646\u0648\u0631\u0648\u0632\u06cc \u062e\u0648\u062f \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0650\u200c\u0631\u0648\u06cc \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u06a9\u0647 \u0628\u0647 \u062e\u0635\u0648\u0635 \u0628\u0627 \u062a\u062d\u0631\u06cc\u0645\u200c\u0647\u0627\u06cc \u0627\u062a\u062d\u0627\u062f\u06cc\u0647 \u0627\u0631\u0648\u067e\u0627 \u0648 \u062f\u0648\u0644\u062a \u0627\u0646\u06af\u0644\u06cc\u0633 \u0639\u0644\u06cc\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u062a\u0634\u062f\u06cc\u062f \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0627\u0638\u0647\u0627\u0631 \u062f\u0627\u0634\u062a: \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062a\u0648\u0627\u0646\u0633\u062a \u0633\u0627\u0644\u06cc \u0645\u0648\u0641\u0642 \u0631\u0627 \u067e\u0634\u062a \u0633\u0631 \u0628\u06af\u0630\u0627\u0631\u062f \u0648 \u0628\u0627 \u0648\u062c\u0648\u062f \u062a\u0645\u0627\u0645\u06cc \u0627\u06cc\u0646 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u060c \u0628\u0627 \u062a\u0644\u0627\u0634 \u0648 \u0647\u0645\u062a \u0633\u062a\u0648\u062f\u0646\u06cc \u062a\u0645\u0627\u0645\u06cc \u0647\u0645\u06a9\u0627\u0631\u0627\u0646 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u0646\u0627\u0648\u06af\u0627\u0646 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0647\u0645\u06a9\u0627\u0631\u0627\u0646 \u067e\u0631\u062a\u0644\u0627\u0634 \u062f\u0631 \u0628\u062e\u0634 \u063a\u06cc\u0631\u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u062a\u0648\u0627\u0646\u0633\u062a \u0628\u0647 \u0631\u0634\u062f \u0686\u0634\u0645\u06af\u06cc\u0631 \u06f1\u06f0\u06f8 \u062f\u0631\u0635\u062f\u06cc \u062f\u0631 \u062f\u0631\u0622\u0645\u062f\u200c\u0647\u0627\u06cc \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062f\u0633\u062a \u06cc\u0627\u0628\u062f.<\/p>\n<\/div>\n<h3><span style=\"color: #3366ff;\">\u0628\u0647\u200c\u06a9\u0627\u0631\u06af\u06cc\u0631\u06cc \u0646\u06cc\u0631\u0648\u200c\u0647\u0627\u06cc \u062c\u0648\u0627\u0646 \u0648 \u0645\u062a\u062e\u0635\u0635 \u0627\u06cc\u0631\u0627\u0646\u06cc<\/span><\/h3>\n<p style=\"font-weight: 400;\">\u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u0628\u0627 \u0627\u0628\u0631\u0627\u0632 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u062a\u062f\u0627\u0648\u0645 \u0627\u06cc\u0646 \u0645\u0648\u0641\u0642\u06cc\u062a \u062f\u0631 \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u062a\u0635\u0631\u06cc\u062d \u06a9\u0631\u062f: \u062a\u0645\u0631\u06a9\u0632 \u0628\u0631 \u062a\u0648\u0633\u0639\u0647 \u0645\u0646\u0627\u0628\u0639 \u0627\u0646\u0633\u0627\u0646\u06cc \u0648 \u0628\u0647\u200c\u06a9\u0627\u0631\u06af\u06cc\u0631\u06cc \u0646\u06cc\u0631\u0648\u200c\u0647\u0627\u06cc \u062c\u0648\u0627\u0646 \u0648 \u0645\u062a\u062e\u0635\u0635 \u0627\u06cc\u0631\u0627\u0646\u06cc\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0627\u0648\u0644\u0648\u06cc\u062a\u200c\u0647\u0627\u06cc \u0646\u0627\u0648\u06af\u0627\u0646 \u0645\u0644\u06cc \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f4 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/p>\n<h3><span style=\"color: #3366ff;\">\u0627\u0647\u062f\u0627\u0641 \u0631\u0627\u0647\u0628\u0631\u062f\u06cc \u062a\u0648\u0633\u0639\u0647 \u0648 \u0646\u0648\u0633\u0627\u0632\u06cc \u0646\u0627\u0648\u06af\u0627\u0646<\/span><\/h3>\n<p style=\"font-weight: 400;\">\u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u0645\u062f\u0631\u0633 \u062e\u06cc\u0627\u0628\u0627\u0646\u06cc \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u062f\u06cc\u06af\u0631 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f4 \u06af\u0641\u062a: \u062a\u0648\u0633\u0639\u0647 \u0648 \u0646\u0648\u0633\u0627\u0632\u06cc \u0646\u0627\u0648\u06af\u0627\u0646\u060c \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0647\u062f\u0627\u0641 \u0631\u0627\u0647\u0628\u0631\u062f\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u062f\u0631 \u062f\u0633\u062a\u0648\u0631 \u06a9\u0627\u0631 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u06a9\u0647 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0622\u0646\u060c \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0627\u06cc \u062c\u0627\u0645\u0639 \u0628\u0631\u0627\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0628\u0647 \u06cc\u06a9 \u0634\u0631\u06a9\u062a \u0644\u062c\u0633\u062a\u06cc\u06a9\u06cc \u067e\u06cc\u0634\u0631\u0648 \u062f\u0631 \u0633\u0637\u062d \u0645\u0646\u0637\u0642\u0647 \u0628\u0627 \u0627\u0631\u0627\u0626\u0647 \u062e\u062f\u0645\u0627\u062a \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u062d\u0645\u0644\u200c\u0648\u200c\u0646\u0642\u0644 \u062f\u0631\u06cc\u0627\u06cc\u06cc\u060c \u062c\u0627\u062f\u0647\u200c\u0627\u06cc \u0648 \u0631\u06cc\u0644\u06cc \u062f\u0631 \u062d\u0627\u0644 \u067e\u06cc\u06af\u06cc\u0631\u06cc \u0627\u0633\u062a.<\/p>\n<p style=\"font-weight: 400;\">\u0648\u06cc \u0627\u0628\u0631\u0627\u0632 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u06cc \u06a9\u0631\u062f: \u0628\u0627 \u062d\u0645\u0627\u06cc\u062a \u0647\u0645\u0647 \u0647\u0645\u06a9\u0627\u0631\u0627\u0646\u060c \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u0648 \u0630\u06cc\u200c\u0646\u0641\u0639\u0627\u0646\u060c \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0628\u062a\u0648\u0627\u0646\u062f \u06af\u0627\u0645\u200c\u0647\u0627\u06cc \u0628\u0644\u0646\u062f\u06cc \u062f\u0631 \u0645\u0633\u06cc\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a \u0648 \u062a\u0639\u0627\u0644\u06cc \u0627\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0628\u0631\u062f\u0627\u0631\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u0631\u0627\u0628\u0631\u0627\u0646 \u0622\u0646\u0644\u0627\u06cc\u0646: \u0645\u062f\u0631\u0633 \u062e\u06cc\u0627\u0628\u0627\u0646\u06cc\u060c\u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0627\u0632 \u062a\u0648\u0633\u0639\u0647 \u0648 \u0646\u0648\u0633\u0627\u0632\u06cc \u0646\u0627\u0648\u06af\u0627\u0646 \u06a9\u0647 \u0627\u0632 \u0627\u0647\u062f\u0627\u0641 \u0631\u0627\u0647\u0628\u0631\u062f\u06cc \u0646\u0627\u0648\u06af\u0627\u0646 \u0645\u0644\u06cc \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f4 \u0627\u0633\u062a \u062e\u0628\u0631 \u062f\u0627\u062f. \u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u06af\u0631\u0648\u0647 \u06a9\u0634\u062a\u06cc\u0631\u0627\u0646\u06cc \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0631\u0634\u062f \u06f1\u06f0\u06f8 \u062f\u0631\u0635\u062f\u06cc \u062f\u0631\u0622\u0645\u062f\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f3\u060c \u0627\u0632 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0631\u06cc\u0632\u06cc \u0628\u0631\u0627\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0628\u0647 \u06cc\u06a9 \u0634\u0631\u06a9\u062a \u0644\u062c\u0633\u062a\u06cc\u06a9\u06cc \u067e\u06cc\u0634\u0631\u0648 \u062f\u0631 [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":2945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-2907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maritime-transport"],"acf":[],"_links":{"self":[{"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/posts\/2907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/comments?post=2907"}],"version-history":[{"count":0,"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/posts\/2907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/media\/2945"}],"wp:attachment":[{"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/media?parent=2907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/categories?post=2907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tarabaran.com\/en\/wp-json\/wp\/v2\/tags?post=2907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}